{"id":1158,"date":"2022-06-15T07:41:41","date_gmt":"2022-06-15T07:41:41","guid":{"rendered":"https:\/\/nicktesting.kinsta.cloud\/shopdiko1\/?page_id=1158"},"modified":"2024-02-07T22:55:53","modified_gmt":"2024-02-07T22:55:53","slug":"about","status":"publish","type":"page","link":"https:\/\/cosmoitalia.net\/index.php\/about\/","title":{"rendered":"About"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1158\" class=\"elementor elementor-1158\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3275fb5 animated-slow elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"3275fb5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d96d2a\" data-id=\"1d96d2a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5362e2 elementor-widget elementor-widget-spacer\" data-id=\"b5362e2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-82be166 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"82be166\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-5e90f98 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"5e90f98\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ef353dd e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"ef353dd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42dea56 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"42dea56\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"755\" height=\"715\" src=\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/MISION.png\" class=\"attachment-large size-large wp-image-6308\" alt=\"\" srcset=\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/MISION.png 755w, https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/MISION-300x284.png 300w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4b84b elementor-widget elementor-widget-text-editor\" data-id=\"7e4b84b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe36761 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"fe36761\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8308502 elementor-widget elementor-widget-spacer\" data-id=\"8308502\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c624aa elementor-widget elementor-widget-heading\" data-id=\"3c624aa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">MISI\u00d3N<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27d74bd elementor-widget elementor-widget-text-editor\" data-id=\"27d74bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ser una distribuidora de \u00a0prestigio ofreciendo a \u00a0nuestros clientes servicios y productos cosm\u00e9ticos de calidad promoviendo marcas de alto \u00a0reconocimiento internacional.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc0f00a e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"fc0f00a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1b4dfe5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"1b4dfe5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5122b2 elementor-widget elementor-widget-spacer\" data-id=\"b5122b2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baabfb0 elementor-widget elementor-widget-heading\" data-id=\"baabfb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VISI\u00d3N<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f50372 elementor-widget elementor-widget-text-editor\" data-id=\"1f50372\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Llegar a ser reconocidos como la empresa m\u00e1s confiable en mercado de cosm\u00e9ticos para el cabello a nivel nacional y la regi\u00f3n centroamericana por nuestra calidad en los productos y puntualidad en el servicio.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-319f96c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"319f96c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64a7a5b elementor-widget elementor-widget-image\" data-id=\"64a7a5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"755\" height=\"715\" src=\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/AMARILLO-2.png\" class=\"attachment-large size-large wp-image-6311\" alt=\"\" srcset=\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/AMARILLO-2.png 755w, https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/AMARILLO-2-300x284.png 300w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfeb6b3 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"dfeb6b3\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ee6fad\" data-id=\"8ee6fad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0c3ecf elementor-widget elementor-widget-heading\" data-id=\"e0c3ecf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Historia<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b83f3c elementor-widget elementor-widget-text-editor\" data-id=\"3b83f3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La empresa salvadore\u00f1a COSMOITALIA S.A. DE C.V., es fundada en el 2016.\u00a0<\/p><p>El nombre de la compa\u00f1\u00eda fue creado con la visi\u00f3n de que se comprenda a que es dedicada, utilizaci\u00f3n las siglas de las palabras \u201cCOSMETICOS ITALIANOS\u201d que dieron lugar al nombre COSMOITALIA, y se cre\u00f3 como slogan \u201cLa belleza es lo nuestro\u201d con el significado de resaltar la belleza del consumidor por medio de productos cosm\u00e9ticos y accesorios de alta calidad.<\/p><p>COSMOITALIA dedicada a la importaci\u00f3n y distribuci\u00f3n de productos de belleza capilar, con el objetivo de llegar a las m\u00e1s prestigiosas salas y spa de belleza del territorio, con el fin de promover las diferentes marcas profesionales procedentes de ITALIA.<\/p><p>Los productos cosm\u00e9ticos importado por COSMOITALIA son productos certificados que cumplen con las reglas de la Comunidad Europea, que promueven el uso de ingredientes amigables con el ambiente y que son comprobados que no da\u00f1an la salud de las personas. Como filosof\u00eda es una empresa orientada a promover las ventas de productos biol\u00f3gicos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c9680d animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"0c9680d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0c46290\" data-id=\"0c46290\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d34efd1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"d34efd1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-caa55f3 elementor-widget elementor-widget-video\" data-id=\"caa55f3\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=oab6CpTCnAk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d2f2c4f\" data-id=\"d2f2c4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc2699 elementor-widget elementor-widget-heading\" data-id=\"2cc2699\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 hacemos?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca778ed elementor-widget elementor-widget-text-editor\" data-id=\"ca778ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>En El Salvador, brindamos &nbsp;productos de alta calidad para el cuidado del cabello y la piel, brindando soluciones efectivas y confiables para mantener una apariencia saludable y radiante. Nuestro compromiso es proporcionar a nuestros clientes los mejores productos y asesoramiento personalizado para lograr resultados \u00f3ptimos en su salud capilar y d\u00e9rmica.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-621a1ad wpr-pbar-title-pos-outside wpr-pbar-counter-pos-outside wpr-prbar-layout-hr-line elementor-widget elementor-widget-wpr-progress-bar\" data-id=\"621a1ad\" data-element_type=\"widget\" data-widget_type=\"wpr-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t<div class=\"wpr-progress-bar\" data-options=\"{&quot;counterValue&quot;:100,&quot;counterValuePersent&quot;:100,&quot;counterSeparator&quot;:&quot;&quot;,&quot;animDuration&quot;:1000,&quot;animDelay&quot;:0,&quot;loop&quot;:&quot;&quot;,&quot;loopDelay&quot;:&quot;&quot;}\">\n\t\t\n\t\t\t<div class=\"wpr-prbar-content elementor-clearfix\"><div class=\"wpr-prbar-title-wrap\"><div class=\"wpr-prbar-title\">Cruelty free<\/div><div class=\"wpr-prbar-subtitle\"><\/div><\/div>\n\t\t<div class=\"wpr-prbar-counter\">\n\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value\">0<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value-suffix\">%<\/span>\n\t\t\t\n\t\t<\/div>\n\n\t\t<\/div>\n\t\t<div class=\"wpr-prbar-hr-line\">\n\t\t\t<div class=\"wpr-prbar-hr-line-inner wpr-anim-timing-ease-default\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e459934 wpr-pbar-title-pos-outside wpr-pbar-counter-pos-outside wpr-prbar-layout-hr-line elementor-widget elementor-widget-wpr-progress-bar\" data-id=\"e459934\" data-element_type=\"widget\" data-widget_type=\"wpr-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t<div class=\"wpr-progress-bar\" data-options=\"{&quot;counterValue&quot;:95,&quot;counterValuePersent&quot;:95,&quot;counterSeparator&quot;:&quot;&quot;,&quot;animDuration&quot;:1000,&quot;animDelay&quot;:0,&quot;loop&quot;:&quot;&quot;,&quot;loopDelay&quot;:&quot;&quot;}\">\n\t\t\n\t\t\t<div class=\"wpr-prbar-content elementor-clearfix\"><div class=\"wpr-prbar-title-wrap\"><div class=\"wpr-prbar-title\">Productos de origen natural<\/div><div class=\"wpr-prbar-subtitle\"><\/div><\/div>\n\t\t<div class=\"wpr-prbar-counter\">\n\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value\">0<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value-suffix\">%<\/span>\n\t\t\t\n\t\t<\/div>\n\n\t\t<\/div>\n\t\t<div class=\"wpr-prbar-hr-line\">\n\t\t\t<div class=\"wpr-prbar-hr-line-inner wpr-anim-timing-ease-default\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de5b9c6 wpr-pbar-title-pos-outside wpr-pbar-counter-pos-outside wpr-prbar-layout-hr-line elementor-widget elementor-widget-wpr-progress-bar\" data-id=\"de5b9c6\" data-element_type=\"widget\" data-widget_type=\"wpr-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t<div class=\"wpr-progress-bar\" data-options=\"{&quot;counterValue&quot;:100,&quot;counterValuePersent&quot;:100,&quot;counterSeparator&quot;:&quot;&quot;,&quot;animDuration&quot;:1000,&quot;animDelay&quot;:0,&quot;loop&quot;:&quot;&quot;,&quot;loopDelay&quot;:&quot;&quot;}\">\n\t\t\n\t\t\t<div class=\"wpr-prbar-content elementor-clearfix\"><div class=\"wpr-prbar-title-wrap\"><div class=\"wpr-prbar-title\">Libre de sulfato<\/div><div class=\"wpr-prbar-subtitle\"><\/div><\/div>\n\t\t<div class=\"wpr-prbar-counter\">\n\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value\">0<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value-suffix\">%<\/span>\n\t\t\t\n\t\t<\/div>\n\n\t\t<\/div>\n\t\t<div class=\"wpr-prbar-hr-line\">\n\t\t\t<div class=\"wpr-prbar-hr-line-inner wpr-anim-timing-ease-default\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03cb071 wpr-pbar-title-pos-outside wpr-pbar-counter-pos-outside wpr-prbar-layout-hr-line elementor-widget elementor-widget-wpr-progress-bar\" data-id=\"03cb071\" data-element_type=\"widget\" data-widget_type=\"wpr-progress-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t<div class=\"wpr-progress-bar\" data-options=\"{&quot;counterValue&quot;:100,&quot;counterValuePersent&quot;:100,&quot;counterSeparator&quot;:&quot;&quot;,&quot;animDuration&quot;:1000,&quot;animDelay&quot;:0,&quot;loop&quot;:&quot;&quot;,&quot;loopDelay&quot;:&quot;&quot;}\">\n\t\t\n\t\t\t<div class=\"wpr-prbar-content elementor-clearfix\"><div class=\"wpr-prbar-title-wrap\"><div class=\"wpr-prbar-title\">Libre de parabenos<\/div><div class=\"wpr-prbar-subtitle\"><\/div><\/div>\n\t\t<div class=\"wpr-prbar-counter\">\n\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value\">0<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"wpr-prbar-counter-value-suffix\">%<\/span>\n\t\t\t\n\t\t<\/div>\n\n\t\t<\/div>\n\t\t<div class=\"wpr-prbar-hr-line\">\n\t\t\t<div class=\"wpr-prbar-hr-line-inner wpr-anim-timing-ease-default\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86156e5 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"86156e5\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a5e8c2\" data-id=\"4a5e8c2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a67fe48 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"a67fe48\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81b7712 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"81b7712\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b77b4ca\" data-id=\"b77b4ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-997cb1a elementor-widget elementor-widget-heading\" data-id=\"997cb1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c38270 elementor-widget elementor-widget-accordion\" data-id=\"6c38270\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 28-02-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1131\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1131\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Estoy teniendo ca\u00edda de cabello \u00bfQu\u00e9 me recomiendas?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1131\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1131\"><p>Recomendamos la linea REFORCE de HELEN SEWARD<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1132\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1132\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfQu\u00e9 productos puedo utilizar para cabello te\u00f1ido?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1132\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1132\"><p>Nuestra linea capilar HYDRA de HELEN SEWARD\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1133\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1133\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfSus productos son cruelty-free y veganos?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1133\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1133\"><p>S\u00ed, todos nuestros productos son cruelty-free y veganos. No realizamos pruebas en animales y nuestros productos no contienen ingredientes de origen animal.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1134\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1134\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfTienen tratamientos especializados para cuidado del cuero cabelludo con caspa, grasa o sensibilidad?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1134\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1134\"><p>S\u00ed, tenemos lineas especializadas para problemas del cuero cabelludo. Puedes escribir al whatsapp tu consulta para atenderte de manera personalizada.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1135\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1135\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00bfPuedo contactar al servicio de atenci\u00f3n al cliente de cosmoitalia en caso de preguntas adicionales?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1135\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1135\"><p>S\u00ed, tenemos una linea telef\u00f3nica y de whasapp exclusiva para atender todas tus consultas. Puedes llamarnos o escribirnos al 7237 3890<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-78691a0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"78691a0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0cdb24 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"c0cdb24\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53586e9\" data-id=\"53586e9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab5c9dc e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"ab5c9dc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de6106c elementor-widget elementor-widget-text-editor\" data-id=\"de6106c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>D\u00e9janos tu n\u00famero de Whatsapp para contactarte y brindarte toda la informaci\u00f3n que necesitas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff8691f elementor-widget elementor-widget-text-editor\" data-id=\"ff8691f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>S\u00famate a m\u00e1s salones certificados<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-478b647 wpr-step-type-number_text wpr-step-content-layout-vertical wpr-custom-styles-yes elementor-widget elementor-widget-wpr-form-builder\" data-id=\"478b647\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:41,&quot;sizes&quot;:[]},&quot;success_message&quot;:&quot;Submission successful&quot;,&quot;error_message&quot;:&quot;Submission failed&quot;,&quot;button_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_content_layout&quot;:&quot;vertical&quot;}\" data-widget_type=\"wpr-form-builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"wpr-form\" method=\"post\" name=\"New Form\" page=\"About\" page_id=\"1158\" novalidate>\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"1158\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"478b647\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"CosmoItalia\" \/>\n\n\t\t\t<div class=\"wpr-step-wrap\"><\/div>\n\t\t\t<div class=\"wpr-form-fields-wrap wpr-labels-\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-form-field-type-text wpr-field-group wpr-column wpr-field-group-phone_whatsapp elementor-repeater-item-4af2593 wpr-form-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-phone_whatsapp\" class=\"wpr-form-field-label wpr-hidden-element\">\n\t\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t<input size=\"1 \"type=\"text\" name=\"form_fields[phone_whatsapp]\" id=\"form-field-phone_whatsapp\" class=\"wpr-form-field  wpr-form-field-textual\" placeholder=\"7777-7777\" required=\"required\" aria-required=\"true\">\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wpr-field-group wpr-stp-btns-wrap wpr-column wpr-form-field-type-submit\" data-actions=\"[&quot;email&quot;]\" data-redirect-url=\"\" data-mailchimp-fields=\"{&quot;email_field&quot;:&quot;&quot;,&quot;first_name_field&quot;:&quot;&quot;,&quot;last_name_field&quot;:&quot;&quot;,&quot;address_field&quot;:&quot;&quot;,&quot;phone_field&quot;:&quot;&quot;,&quot;birthday_field&quot;:&quot;&quot;,&quot;group_id&quot;:&quot;&quot;}\" data-list-id=\"\">\t\t\t<button type=\"submit\" class=\"wpr-button\" id=\"btn-certificate\">\n\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Certificate<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\t\n\t\t\t\t<div class=\"wpr-double-bounce wpr-loader-hidden\">\n\t\t\t\t\t<div class=\"wpr-child wpr-double-bounce1\"><\/div>\n\t\t\t\t\t<div class=\"wpr-child wpr-double-bounce2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/button>\n\t\t<\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/form>\n\t  \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MISI\u00d3N Ser una distribuidora de \u00a0prestigio ofreciendo a \u00a0nuestros clientes servicios y productos cosm\u00e9ticos de calidad promoviendo marcas de alto \u00a0reconocimiento internacional. VISI\u00d3N Llegar a ser reconocidos como la empresa m\u00e1s confiable en mercado de cosm\u00e9ticos para el cabello a nivel nacional y la regi\u00f3n centroamericana por nuestra calidad en los productos y puntualidad en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-1158","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>About - CosmoItalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmoitalia.net\/index.php\/about\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About - CosmoItalia\" \/>\n<meta property=\"og:description\" content=\"MISI\u00d3N Ser una distribuidora de \u00a0prestigio ofreciendo a \u00a0nuestros clientes servicios y productos cosm\u00e9ticos de calidad promoviendo marcas de alto \u00a0reconocimiento internacional. VISI\u00d3N Llegar a ser reconocidos como la empresa m\u00e1s confiable en mercado de cosm\u00e9ticos para el cabello a nivel nacional y la regi\u00f3n centroamericana por nuestra calidad en los productos y puntualidad en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmoitalia.net\/index.php\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"CosmoItalia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T22:55:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/MISION.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cosmoitalia.net\/index.php\/about\/\",\"url\":\"https:\/\/cosmoitalia.net\/index.php\/about\/\",\"name\":\"About - CosmoItalia\",\"isPartOf\":{\"@id\":\"https:\/\/cosmoitalia.net\/#website\"},\"datePublished\":\"2022-06-15T07:41:41+00:00\",\"dateModified\":\"2024-02-07T22:55:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cosmoitalia.net\/index.php\/about\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cosmoitalia.net\/index.php\/about\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cosmoitalia.net\/index.php\/about\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/cosmoitalia.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cosmoitalia.net\/#website\",\"url\":\"https:\/\/cosmoitalia.net\/\",\"name\":\"CosmoItalia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cosmoitalia.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cosmoitalia.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cosmoitalia.net\/#organization\",\"name\":\"CosmoItalia\",\"url\":\"https:\/\/cosmoitalia.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cosmoitalia.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2023\/09\/cropped-cropped-LOGO_COSMOITALIA-preview-1.png\",\"contentUrl\":\"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2023\/09\/cropped-cropped-LOGO_COSMOITALIA-preview-1.png\",\"width\":498,\"height\":142,\"caption\":\"CosmoItalia\"},\"image\":{\"@id\":\"https:\/\/cosmoitalia.net\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About - CosmoItalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmoitalia.net\/index.php\/about\/","og_locale":"es_MX","og_type":"article","og_title":"About - CosmoItalia","og_description":"MISI\u00d3N Ser una distribuidora de \u00a0prestigio ofreciendo a \u00a0nuestros clientes servicios y productos cosm\u00e9ticos de calidad promoviendo marcas de alto \u00a0reconocimiento internacional. VISI\u00d3N Llegar a ser reconocidos como la empresa m\u00e1s confiable en mercado de cosm\u00e9ticos para el cabello a nivel nacional y la regi\u00f3n centroamericana por nuestra calidad en los productos y puntualidad en [&hellip;]","og_url":"https:\/\/cosmoitalia.net\/index.php\/about\/","og_site_name":"CosmoItalia","article_modified_time":"2024-02-07T22:55:53+00:00","og_image":[{"url":"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2024\/01\/MISION.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmoitalia.net\/index.php\/about\/","url":"https:\/\/cosmoitalia.net\/index.php\/about\/","name":"About - CosmoItalia","isPartOf":{"@id":"https:\/\/cosmoitalia.net\/#website"},"datePublished":"2022-06-15T07:41:41+00:00","dateModified":"2024-02-07T22:55:53+00:00","breadcrumb":{"@id":"https:\/\/cosmoitalia.net\/index.php\/about\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmoitalia.net\/index.php\/about\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cosmoitalia.net\/index.php\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cosmoitalia.net\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/cosmoitalia.net\/#website","url":"https:\/\/cosmoitalia.net\/","name":"CosmoItalia","description":"","publisher":{"@id":"https:\/\/cosmoitalia.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmoitalia.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cosmoitalia.net\/#organization","name":"CosmoItalia","url":"https:\/\/cosmoitalia.net\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cosmoitalia.net\/#\/schema\/logo\/image\/","url":"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2023\/09\/cropped-cropped-LOGO_COSMOITALIA-preview-1.png","contentUrl":"https:\/\/cosmoitalia.net\/wp-content\/uploads\/2023\/09\/cropped-cropped-LOGO_COSMOITALIA-preview-1.png","width":498,"height":142,"caption":"CosmoItalia"},"image":{"@id":"https:\/\/cosmoitalia.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/pages\/1158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/comments?post=1158"}],"version-history":[{"count":0,"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/pages\/1158\/revisions"}],"wp:attachment":[{"href":"https:\/\/cosmoitalia.net\/index.php\/wp-json\/wp\/v2\/media?parent=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}